{"id":22601,"date":"2026-05-13T10:42:59","date_gmt":"2026-05-13T13:42:59","guid":{"rendered":"https:\/\/www.noticiasmas.com.ar\/?p=22601"},"modified":"2026-05-13T10:43:04","modified_gmt":"2026-05-13T13:43:04","slug":"iriondo-comenzo-la-formacion-de-gasistas-domiciliarios-para-potenciar-el-empleo-regional","status":"publish","type":"post","link":"https:\/\/www.noticiasmas.com.ar\/index.php\/2026\/05\/13\/iriondo-comenzo-la-formacion-de-gasistas-domiciliarios-para-potenciar-el-empleo-regional\/","title":{"rendered":"Iriondo: Comenz\u00f3 la formaci\u00f3n de gasistas domiciliarios para potenciar el empleo regional"},"content":{"rendered":"\n<p>En un paso estrat\u00e9gico para el desarrollo laboral del departamento Iriondo, se puso en marcha el Curso de Gasista Domiciliario para la Ruta 34 en las instalaciones de la Escuela T\u00e9cnica N\u00b0 482 de la ciudad de Totoras. Esta iniciativa busca brindar herramientas t\u00e9cnicas y una salida laboral inmediata a vecinos y vecinas, en un contexto marcado por la expansi\u00f3n de la infraestructura energ\u00e9tica en la regi\u00f3n.<\/p>\n\n\n\n<p><br>La capacitaci\u00f3n cuenta con la certificaci\u00f3n oficial del Ministerio de Educaci\u00f3n de la Provincia de Santa Fe, lo que garantiza que los egresados obtendr\u00e1n t\u00edtulos habilitantes para realizar instalaciones de gas seguras y bajo normativa. El inicio del curso responde a una futura demanda \u00f1 de mano de obra calificada, impulsada principalmente por la llegada del gasoducto de la ruta 34, una obra que transformar\u00e1 la matriz productiva y la calidad de vida de las localidades vecinas.<\/p>\n\n\n\n<p><br>El senador Hugo Jes\u00fas Rasetto destac\u00f3 la importancia de anticiparse a los cambios estructurales de la regi\u00f3n:<br>&#8220;Esta capacitaci\u00f3n es una respuesta concreta a las necesidades que vienen de la mano del gasoducto de la ruta 34. No solo estamos brindando conocimientos t\u00e9cnicos, sino que estamos preparando a nuestra gente para que el progreso se quede ac\u00e1, transformando el aprendizaje en trabajo real y digno para cada familia. Ver a tantos vecinos comprometidos con su formaci\u00f3n nos llena de esperanza porque ellos son el motor del crecimiento de nuestro departamento&#8221;.<\/p>\n\n\n\n<p><br>La jornada de bienvenida cont\u00f3 con la participaci\u00f3n del director del establecimiento, Mauricio Su\u00e1rez; la delegada de la Regi\u00f3n V de Educaci\u00f3n, Marisa Pr\u00edncipe; el supervisor de Formaci\u00f3n Profesional, Gustavo Pasquinelli; y representantes del municipio local, entre ellos la secretaria de Gobierno, Ma. Emilia Vacchieri, y la responsable del \u00e1rea de Producci\u00f3n, Natalia Santos.<\/p>\n\n\n\n<p><br>Con esta nueva propuesta, se reafirma el compromiso con la educaci\u00f3n t\u00e9cnica y la formaci\u00f3n profesional como pilares fundamentales para generar nuevas oportunidades y fortalecer el tejido productivo del departamento Iriondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un paso estrat\u00e9gico para el desarrollo laboral del departamento Iriondo, se puso en marcha el Curso de Gasista Domiciliario para la Ruta 34 en las instalaciones de la Escuela T\u00e9cnica N\u00b0 482 de la ciudad de Totoras. Esta iniciativa busca brindar herramientas t\u00e9cnicas y una salida laboral inmediata a vecinos y vecinas, en un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":22603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[13],"tags":[6925,1345,1591,2236],"class_list":{"0":"post-22601","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-region","8":"tag-curso-de-gasista-matriculado","9":"tag-departamento-iriondo","10":"tag-hugo-rasetto","11":"tag-totoras"},"_links":{"self":[{"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=22601"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22601\/revisions"}],"predecessor-version":[{"id":22604,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22601\/revisions\/22604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/media\/22603"}],"wp:attachment":[{"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=22601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=22601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=22601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}