{"id":22608,"date":"2026-05-13T14:18:12","date_gmt":"2026-05-13T17:18:12","guid":{"rendered":"https:\/\/www.noticiasmas.com.ar\/?p=22608"},"modified":"2026-05-13T14:18:18","modified_gmt":"2026-05-13T17:18:18","slug":"prohibieron-jugar-a-un-futbolista-de-la-totorense-por-ser-deudor-alimentario","status":"publish","type":"post","link":"https:\/\/www.noticiasmas.com.ar\/index.php\/2026\/05\/13\/prohibieron-jugar-a-un-futbolista-de-la-totorense-por-ser-deudor-alimentario\/","title":{"rendered":"Prohibieron jugar a un futbolista de la Totorense por ser deudor alimentario"},"content":{"rendered":"\n<p>Un futbolista del Club Atl\u00e9tico San Genaro recibi\u00f3 una inhabilitaci\u00f3n por disposici\u00f3n de la Justicia de Familia de San Lorenzo por ser deudor alimenetario y no podr\u00e1 continuar jugando los partidos de la Liga Totorense de F\u00fatbol.<\/p>\n\n\n\n<p>El futbolista Carlos Emanuel S., qued\u00f3 inhabilitado por el Tribunal de Disciplina de la Totorense haciendo valer una \u00f3rden judicial expedida por el Juzgado de Familia de San Lorenzo, ya que la situaci\u00f3n legal fue denunciada en la regi\u00f3n.&nbsp;<\/p>\n\n\n\n<p>A trav\u00e9s del&nbsp;Oficio Judicial N.\u00ba 1052, remitido por el Juzgado de Familia de San Lorenzo, el jugador qued\u00f3 inhabilitado \u201cpara desempe\u00f1arse como jugador dentro de esta Liga, as\u00ed como tambi\u00e9n en cualquier instituci\u00f3n o club afiliado e integrante de la misma. Asimismo, se deja constancia de que dicha medida tendr\u00e1 plena vigencia hasta tanto exista resoluci\u00f3n judicial en contrario emitida por la autoridad competente\u201d.<\/p>\n\n\n\n<p>Se trata del primer caso donde la Justicia expide una sanci\u00f3n que se efectiviza a trav\u00e9s del reglamento de un torneo deportivo.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un futbolista del Club Atl\u00e9tico San Genaro recibi\u00f3 una inhabilitaci\u00f3n por disposici\u00f3n de la Justicia de Familia de San Lorenzo por ser deudor alimenetario y no podr\u00e1 continuar jugando los partidos de la Liga Totorense de F\u00fatbol. El futbolista Carlos Emanuel S., qued\u00f3 inhabilitado por el Tribunal de Disciplina de la Totorense haciendo valer una [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":22609,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[9],"tags":[46,98,219],"class_list":{"0":"post-22608","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales","8":"tag-futbol","9":"tag-judiciales","10":"tag-liga-totorense"},"_links":{"self":[{"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=22608"}],"version-history":[{"count":1,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22608\/revisions"}],"predecessor-version":[{"id":22610,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22608\/revisions\/22610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/media\/22609"}],"wp:attachment":[{"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=22608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=22608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noticiasmas.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=22608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}